{"id":8185,"date":"2022-12-02T12:28:44","date_gmt":"2022-12-02T11:28:44","guid":{"rendered":"https:\/\/domusrs.com\/2022\/12\/02\/a-domus-residential-services-atinge-80-de-mulheres-na-forca-de-trabalho\/"},"modified":"2024-01-29T14:35:22","modified_gmt":"2024-01-29T13:35:22","slug":"a-domus-residential-services-atinge-80-de-mulheres-na-forca-de-trabalho","status":"publish","type":"post","link":"https:\/\/domusrs.com\/pt-pt\/2022\/12\/02\/a-domus-residential-services-atinge-80-de-mulheres-na-forca-de-trabalho\/","title":{"rendered":"A Domus Residential Services atinge 80% de mulheres na for\u00e7a de trabalho"},"content":{"rendered":"\n<p><strong>A Domus Residential Services, uma plataforma espanhola de gest\u00e3o integrada focada no mercado residencial desde 2013, alargou recentemente o seu quadro de pessoal. Enquanto em janeiro deste ano a equipa era constitu\u00edda por 21 profissionais na folha de pagamentos, hoje s\u00e3o mais de 60, atingindo 80% de mulheres na empresa.<\/strong><\/p>\n\n<p>A assinatura do perito no sector imobili\u00e1rio, nomeadamente no mercado residencial granular e atomizado,  <strong>Noelia Iturriaga<\/strong>A nova equipa de profissionais, para al\u00e9m dos outros profissionais dos diferentes escrit\u00f3rios da Domus RS em diferentes partes de Espanha e Portugal. &#8220;<em>Estou perante um projeto aliciante, em que, para al\u00e9m da forma\u00e7\u00e3o de uma equipa nacional e da sua gest\u00e3o, o n\u00famero de activos sob gest\u00e3o \u00e9 substancial e importante.<\/em>&#8220;O novo diretor de gest\u00e3o e vendas de produtos atomizados e granulados da empresa salienta.<\/p>\n\n<p>Este crescimento do capital humano \u00e9 mais uma demonstra\u00e7\u00e3o do<strong> seu compromisso com a for\u00e7a do talento e, em geral, com a \u00e1rea dos Recursos Humanos<\/strong>.<\/p>\n\n<p><strong>Uma equipa multidisciplinar, especializada e altamente qualificada, a espinha dorsal da Domus RS<\/strong><\/p>\n\n<p>Sempre <strong>motivados pelo trabalho em equipa, pela soma de experi\u00eancias e pela aprendizagem cont\u00ednua<\/strong>, <strong>os profissionais da Domus RS<\/strong> s\u00e3o especializados no sector do desenvolvimento, na banca e na consultoria nacional, entre outras \u00e1reas. Al\u00e9m disso, os seus quadros incluem especialistas em desenvolvimento e marketing imobili\u00e1rio, bem como especialistas em <strong>marketing e recursos humanos<\/strong>. A equipa j\u00e1 tem <strong>escrit\u00f3rios em praticamente<\/strong> todos os <strong>pontos estrat\u00e9gicos de Espanha e parte de Portugal (Lisboa e Algarve)<\/strong>, estando prestes a abrir o seu primeiro escrit\u00f3rio em Bilbau e a avaliar cuidadosamente a abertura do seu escrit\u00f3rio em It\u00e1lia.<\/p>\n\n<p>Os colaboradores da Domus RS trabalham numa vasta gama de servi\u00e7os relacionados com a <strong>gest\u00e3o de activos imobili\u00e1rios, para al\u00e9m da comercializa\u00e7\u00e3o de novos im\u00f3veis<\/strong>. A sua equipa <strong>diversificada e multidisciplinar<\/strong> supervisiona a divis\u00e3o de comercializa\u00e7\u00e3o de activos banc\u00e1rios (ou de bens disseminados ou granulares executados), gra\u00e7as a um trabalho comum realizado diariamente a partir da sua vasta rede de ag\u00eancias.<\/p>\n\n<p>Mas estas n\u00e3o s\u00e3o as \u00fanicas vias estrat\u00e9gicas atrav\u00e9s das quais a empresa actua. Entre as suas especialidades est\u00e1 o servi\u00e7o de <strong>gest\u00e3o de activos ou de promotores delegados para fundos ou investidores que n\u00e3o disp\u00f5em de estrutura pr\u00f3pria<\/strong>; um exemplo disso s\u00e3o os projectos que a Domus RS est\u00e1 a desenvolver no Algarve portugu\u00eas.<\/p>\n\n<p><strong>Noelia Iturriaga, nova directora de gest\u00e3o e vendas de produtos secos por pulveriza\u00e7\u00e3o e granulados.<\/strong><\/p>\n\n<p>Como resultado das suas \u00faltimas incorpora\u00e7\u00f5es de talento, Noelia Iturriaga juntou-se \u00e0 empresa como <strong>nova respons\u00e1vel pela \u00e1rea de gest\u00e3o e vendas de produtos atomizados e granulados<\/strong>. Especialista em imobili\u00e1rio, lideran\u00e7a e marketing, tem mais de 20 anos de experi\u00eancia no sector. Noelia tem tamb\u00e9m uma vasta experi\u00eancia e conhecimento do mercado, tendo desempenhado v\u00e1rios cargos de responsabilidade, tanto comerciais como t\u00e9cnicos.<\/p>\n\n<p>Desta forma, o profissional enfrenta agora uma nova etapa profissional nas fileiras da plataforma de gest\u00e3o integrada destinada ao mercado residencial. A contrata\u00e7\u00e3o de Noelia Iturriaga <strong>simboliza mais um passo no compromisso da empresa para com a igualdade de g\u00e9nero<\/strong>. Esta \u00e9 uma das \u00e1reas mais importantes para a plataforma, que a implementa atrav\u00e9s da sua \u00e1rea de Recursos Humanos em colabora\u00e7\u00e3o com a \u00e1rea de Responsabilidade Social Corporativa.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>A Domus Residential Services, uma plataforma espanhola de gest\u00e3o integrada focada no mercado residencial desde 2013, alargou recentemente o seu quadro de pessoal. Enquanto em janeiro deste ano a equipa era constitu\u00edda por 21 profissionais na folha de pagamentos, hoje s\u00e3o mais de 60, atingindo 80% de mulheres na empresa. A assinatura do perito no [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":8187,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[55],"tags":[],"class_list":["post-8185","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-sem-categoria"],"_links":{"self":[{"href":"https:\/\/domusrs.com\/pt-pt\/wp-json\/wp\/v2\/posts\/8185","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/domusrs.com\/pt-pt\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/domusrs.com\/pt-pt\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/domusrs.com\/pt-pt\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/domusrs.com\/pt-pt\/wp-json\/wp\/v2\/comments?post=8185"}],"version-history":[{"count":1,"href":"https:\/\/domusrs.com\/pt-pt\/wp-json\/wp\/v2\/posts\/8185\/revisions"}],"predecessor-version":[{"id":8189,"href":"https:\/\/domusrs.com\/pt-pt\/wp-json\/wp\/v2\/posts\/8185\/revisions\/8189"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/domusrs.com\/pt-pt\/wp-json\/wp\/v2\/media\/8187"}],"wp:attachment":[{"href":"https:\/\/domusrs.com\/pt-pt\/wp-json\/wp\/v2\/media?parent=8185"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/domusrs.com\/pt-pt\/wp-json\/wp\/v2\/categories?post=8185"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/domusrs.com\/pt-pt\/wp-json\/wp\/v2\/tags?post=8185"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}